{"id":930,"date":"2024-04-22T09:50:42","date_gmt":"2024-04-22T07:50:42","guid":{"rendered":"https:\/\/hirzerseilbahn.it\/tal-mittel-und-bergstation\/"},"modified":"2024-06-12T08:51:47","modified_gmt":"2024-06-12T06:51:47","slug":"stazione-di-valle-media-e-montagna","status":"publish","type":"page","link":"https:\/\/hirzerseilbahn.it\/it\/stazione-di-valle-media-e-montagna\/","title":{"rendered":"Stazione di valle, media e montagna"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; full_height=&#8221;yes&#8221; columns_placement=&#8221;stretch&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;1523&#8243; background_image_position=&#8221;center center&#8221; background_image_stacking=&#8221;default&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;500&#8243;][\/vc_column][vc_column column_padding=&#8221;padding-8-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Stazione di valle, media e montagna&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23d50001&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1715759683252{padding-bottom: 5% !important;}&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;border-animation&#8221; icon_border_thickness=&#8221;1px&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-3&#8243; icon_padding=&#8221;15px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Cable-Car&#8221; icon_size=&#8221;30&#8243;][vc_custom_heading text=&#8221;Stazione a valle&#8221; font_container=&#8221;tag:h4|text_align:left|color:%23d50001&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]La stazione a valle <strong>della funivia Hirzer<\/strong> si trova in Val Passiria, a Saltusio (frazione di San Martino), a <strong>490 metri<\/strong> sopra il livello del mare. A pochi passi dalla stazione vi \u00e8 una fermata della <strong>linea di autobus<\/strong> Merano &#8211; val Passiria.[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;border-animation&#8221; icon_border_thickness=&#8221;1px&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-3&#8243; icon_padding=&#8221;15px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Cable-Car&#8221; icon_size=&#8221;30&#8243;][vc_custom_heading text=&#8221;Stazione intermedia&#8221; font_container=&#8221;tag:h4|text_align:left|color:%23d50001&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Dalla stazione di <strong>intermedia di Prenn,<\/strong> a <strong>1.404 metri<\/strong> sopra il livello del mare, si accede agevolmente alla rete di sentieri del Cervina. Pertanto, \u00e8 un <strong>ottimo punto<\/strong> di partenza e di arrivo per una serie di escursioni. In zona vi sono vari punti di ristoro.[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;border-animation&#8221; icon_border_thickness=&#8221;1px&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-3&#8243; icon_padding=&#8221;15px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Cable-Car&#8221; icon_size=&#8221;30&#8243;][vc_custom_heading text=&#8221;Stazione a monte&#8221; font_container=&#8221;tag:h4|text_align:left|color:%23d50001&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]La <strong>stazione montana<\/strong> di Klammeben, a <strong>1.980 metri<\/strong> sopra il livello del mare, \u00e8 la porta di accesso alla zona escursionistica del Cervina. Da qui, potrete andare alla scoperta della <strong>fauna e flora alpina<\/strong>, avventurandovi lungo la fitta rete di sentieri, che offre intinerari di vari gradi di difficolt\u00e0. L&#8217;altipiano del Cervina \u00e8 adatto sia alle famiglie sia agli <strong>alpinisti esperti<\/strong>, che potranno cimentarsi nell&#8217;ascesa alla vetta del massiccio del Cervina.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1715759896402{padding-top: 3% !important;}&#8221; text_direction=&#8221;default&#8221;]Per ulteriori informazioni, contattateci all&#8217;indirizzo<br \/>\n<a href=\"tel:+390473645498\">+39 0473 645498<\/a>.[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; full_height=&#8221;yes&#8221; columns_placement=&#8221;stretch&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-930","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stazione di valle, media e montagna &#8211; Hirzer Seilbahn<\/title>\n<meta name=\"description\" content=\"La stazione a valle \u00e8 il punto di partenza della funivia di Hirzer, mentre la stazione intermedia di Prenn \u00e8 ideale per le escursioni a 1.404 metri di altitudine.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hirzerseilbahn.it\/it\/stazione-di-valle-media-e-montagna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stazione di valle, media e montagna &#8211; Hirzer Seilbahn\" \/>\n<meta property=\"og:description\" content=\"La stazione a valle \u00e8 il punto di partenza della funivia di Hirzer, mentre la stazione intermedia di Prenn \u00e8 ideale per le escursioni a 1.404 metri di altitudine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hirzerseilbahn.it\/it\/stazione-di-valle-media-e-montagna\/\" \/>\n<meta property=\"og:site_name\" content=\"Hirzer Seilbahn\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61558775782206\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-12T06:51:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/it\\\/stazione-di-valle-media-e-montagna\\\/\",\"url\":\"https:\\\/\\\/hirzerseilbahn.it\\\/it\\\/stazione-di-valle-media-e-montagna\\\/\",\"name\":\"Stazione di valle, media e montagna &#8211; Hirzer Seilbahn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/#website\"},\"datePublished\":\"2024-04-22T07:50:42+00:00\",\"dateModified\":\"2024-06-12T06:51:47+00:00\",\"description\":\"La stazione a valle \u00e8 il punto di partenza della funivia di Hirzer, mentre la stazione intermedia di Prenn \u00e8 ideale per le escursioni a 1.404 metri di altitudine.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/it\\\/stazione-di-valle-media-e-montagna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hirzerseilbahn.it\\\/it\\\/stazione-di-valle-media-e-montagna\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/it\\\/stazione-di-valle-media-e-montagna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hirzerseilbahn.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stazione di valle, media e montagna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/#website\",\"url\":\"https:\\\/\\\/hirzerseilbahn.it\\\/\",\"name\":\"Hirzer Seilbahn\",\"description\":\"Die Hirzer Seilbahn in Passeiertal\",\"publisher\":{\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hirzerseilbahn.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/#organization\",\"name\":\"Hirzer Seilbahn\",\"url\":\"https:\\\/\\\/hirzerseilbahn.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hirzerseilbahn.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logoROT_800px.png\",\"contentUrl\":\"https:\\\/\\\/hirzerseilbahn.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logoROT_800px.png\",\"width\":512,\"height\":512,\"caption\":\"Hirzer Seilbahn\"},\"image\":{\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61558775782206\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stazione di valle, media e montagna &#8211; Hirzer Seilbahn","description":"La stazione a valle \u00e8 il punto di partenza della funivia di Hirzer, mentre la stazione intermedia di Prenn \u00e8 ideale per le escursioni a 1.404 metri di altitudine.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hirzerseilbahn.it\/it\/stazione-di-valle-media-e-montagna\/","og_locale":"it_IT","og_type":"article","og_title":"Stazione di valle, media e montagna &#8211; Hirzer Seilbahn","og_description":"La stazione a valle \u00e8 il punto di partenza della funivia di Hirzer, mentre la stazione intermedia di Prenn \u00e8 ideale per le escursioni a 1.404 metri di altitudine.","og_url":"https:\/\/hirzerseilbahn.it\/it\/stazione-di-valle-media-e-montagna\/","og_site_name":"Hirzer Seilbahn","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61558775782206","article_modified_time":"2024-06-12T06:51:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hirzerseilbahn.it\/it\/stazione-di-valle-media-e-montagna\/","url":"https:\/\/hirzerseilbahn.it\/it\/stazione-di-valle-media-e-montagna\/","name":"Stazione di valle, media e montagna &#8211; Hirzer Seilbahn","isPartOf":{"@id":"https:\/\/hirzerseilbahn.it\/#website"},"datePublished":"2024-04-22T07:50:42+00:00","dateModified":"2024-06-12T06:51:47+00:00","description":"La stazione a valle \u00e8 il punto di partenza della funivia di Hirzer, mentre la stazione intermedia di Prenn \u00e8 ideale per le escursioni a 1.404 metri di altitudine.","breadcrumb":{"@id":"https:\/\/hirzerseilbahn.it\/it\/stazione-di-valle-media-e-montagna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hirzerseilbahn.it\/it\/stazione-di-valle-media-e-montagna\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hirzerseilbahn.it\/it\/stazione-di-valle-media-e-montagna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hirzerseilbahn.it\/it\/"},{"@type":"ListItem","position":2,"name":"Stazione di valle, media e montagna"}]},{"@type":"WebSite","@id":"https:\/\/hirzerseilbahn.it\/#website","url":"https:\/\/hirzerseilbahn.it\/","name":"Hirzer Seilbahn","description":"Die Hirzer Seilbahn in Passeiertal","publisher":{"@id":"https:\/\/hirzerseilbahn.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hirzerseilbahn.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/hirzerseilbahn.it\/#organization","name":"Hirzer Seilbahn","url":"https:\/\/hirzerseilbahn.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hirzerseilbahn.it\/#\/schema\/logo\/image\/","url":"https:\/\/hirzerseilbahn.it\/wp-content\/uploads\/2024\/04\/logoROT_800px.png","contentUrl":"https:\/\/hirzerseilbahn.it\/wp-content\/uploads\/2024\/04\/logoROT_800px.png","width":512,"height":512,"caption":"Hirzer Seilbahn"},"image":{"@id":"https:\/\/hirzerseilbahn.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61558775782206"]}]}},"_links":{"self":[{"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/pages\/930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/comments?post=930"}],"version-history":[{"count":9,"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/pages\/930\/revisions"}],"predecessor-version":[{"id":1585,"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/pages\/930\/revisions\/1585"}],"wp:attachment":[{"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/media?parent=930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}