{"id":975,"date":"2024-04-22T09:55:56","date_gmt":"2024-04-22T07:55:56","guid":{"rendered":"https:\/\/hirzerseilbahn.it\/webcam\/"},"modified":"2024-05-14T08:54:54","modified_gmt":"2024-05-14T06:54:54","slug":"webcam","status":"publish","type":"page","link":"https:\/\/hirzerseilbahn.it\/it\/webcam\/","title":{"rendered":"Webcam"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;4%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_blank&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; column_link=&#8221;https:\/\/www.bergfex.it\/sommer\/schenna\/webcams\/c17611\/&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;WEBCAM HIRZER&#8221; font_container=&#8221;tag:h2|font_size:50px|text_align:center|color:%23d50001|line_height:50px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_raw_html css=&#8221;&#8221;]PGRpdiBpZD0iYzk3IiBjbGFzcz0iZnJhbWUgZnJhbWUtZGVmYXVsdCBmcmFtZS10eXBlLWh0bWwgZnJhbWUtbGF5b3V0LTAgZnJhbWUtc3BhY2UtYmVmb3JlLW1lZGl1bSI+PGltZyBzcmM9Imh0dHBzOi8vZnRwLnNjaGVubmEuY29tL3dlYmNhbXMvaGlyemVyLmpwZyIgd2lkdGg9IjcyOHB4IiBoZWlnaHQ9IjU1MHB4IiBmcmFtZWJvcmRlcj0iMCIgc2Nyb2xsaW5nPSJubyI+PC9kaXY+[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;4%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-975","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Webcam &#8211; Hirzer Seilbahn<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hirzerseilbahn.it\/it\/webcam\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Webcam &#8211; Hirzer Seilbahn\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;4%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hirzerseilbahn.it\/it\/webcam\/\" \/>\n<meta property=\"og:site_name\" content=\"Hirzer Seilbahn\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61558775782206\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-14T06:54:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/it\\\/webcam\\\/\",\"url\":\"https:\\\/\\\/hirzerseilbahn.it\\\/it\\\/webcam\\\/\",\"name\":\"Webcam &#8211; Hirzer Seilbahn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/#website\"},\"datePublished\":\"2024-04-22T07:55:56+00:00\",\"dateModified\":\"2024-05-14T06:54:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/it\\\/webcam\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hirzerseilbahn.it\\\/it\\\/webcam\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/it\\\/webcam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hirzerseilbahn.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webcam\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/#website\",\"url\":\"https:\\\/\\\/hirzerseilbahn.it\\\/\",\"name\":\"Hirzer Seilbahn\",\"description\":\"Die Hirzer Seilbahn in Passeiertal\",\"publisher\":{\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hirzerseilbahn.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/#organization\",\"name\":\"Hirzer Seilbahn\",\"url\":\"https:\\\/\\\/hirzerseilbahn.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hirzerseilbahn.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logoROT_800px.png\",\"contentUrl\":\"https:\\\/\\\/hirzerseilbahn.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logoROT_800px.png\",\"width\":512,\"height\":512,\"caption\":\"Hirzer Seilbahn\"},\"image\":{\"@id\":\"https:\\\/\\\/hirzerseilbahn.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61558775782206\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Webcam &#8211; Hirzer Seilbahn","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hirzerseilbahn.it\/it\/webcam\/","og_locale":"it_IT","og_type":"article","og_title":"Webcam &#8211; Hirzer Seilbahn","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;4%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;...","og_url":"https:\/\/hirzerseilbahn.it\/it\/webcam\/","og_site_name":"Hirzer Seilbahn","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61558775782206","article_modified_time":"2024-05-14T06:54:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hirzerseilbahn.it\/it\/webcam\/","url":"https:\/\/hirzerseilbahn.it\/it\/webcam\/","name":"Webcam &#8211; Hirzer Seilbahn","isPartOf":{"@id":"https:\/\/hirzerseilbahn.it\/#website"},"datePublished":"2024-04-22T07:55:56+00:00","dateModified":"2024-05-14T06:54:54+00:00","breadcrumb":{"@id":"https:\/\/hirzerseilbahn.it\/it\/webcam\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hirzerseilbahn.it\/it\/webcam\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hirzerseilbahn.it\/it\/webcam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hirzerseilbahn.it\/it\/"},{"@type":"ListItem","position":2,"name":"Webcam"}]},{"@type":"WebSite","@id":"https:\/\/hirzerseilbahn.it\/#website","url":"https:\/\/hirzerseilbahn.it\/","name":"Hirzer Seilbahn","description":"Die Hirzer Seilbahn in Passeiertal","publisher":{"@id":"https:\/\/hirzerseilbahn.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hirzerseilbahn.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/hirzerseilbahn.it\/#organization","name":"Hirzer Seilbahn","url":"https:\/\/hirzerseilbahn.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hirzerseilbahn.it\/#\/schema\/logo\/image\/","url":"https:\/\/hirzerseilbahn.it\/wp-content\/uploads\/2024\/04\/logoROT_800px.png","contentUrl":"https:\/\/hirzerseilbahn.it\/wp-content\/uploads\/2024\/04\/logoROT_800px.png","width":512,"height":512,"caption":"Hirzer Seilbahn"},"image":{"@id":"https:\/\/hirzerseilbahn.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61558775782206"]}]}},"_links":{"self":[{"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/pages\/975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/comments?post=975"}],"version-history":[{"count":2,"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/pages\/975\/revisions"}],"predecessor-version":[{"id":977,"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/pages\/975\/revisions\/977"}],"wp:attachment":[{"href":"https:\/\/hirzerseilbahn.it\/it\/wp-json\/wp\/v2\/media?parent=975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}